{"id":178,"date":"2022-05-30T14:35:01","date_gmt":"2022-05-30T17:35:01","guid":{"rendered":"http:\/\/localhost\/subsole\/?post_type=variedades&#038;p=178"},"modified":"2022-06-06T11:04:09","modified_gmt":"2022-06-06T14:04:09","slug":"allison","status":"publish","type":"variedades","link":"https:\/\/subsole.fuegoclients.com\/web\/frutas\/uvas-de-mesa\/variedades\/allison\/","title":{"rendered":"Allison"},"parent":0,"template":"","class_list":["post-178","variedades","type-variedades","status-publish","hentry"],"translation":{"provider":"WPGlobus","version":"2.10.1","language":"es","enabled_languages":["es","en"],"languages":{"es":{"title":true,"content":false,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Variedad Allison la m\u00e1s dulce &mdash; Subsole<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Variedad Allison la m\u00e1s dulce &mdash; Subsole\" \/>\n<meta property=\"og:url\" content=\"https:\/\/subsole.fuegoclients.com\/web\/frutas\/uvas-de-mesa\/variedades\/allison\/\" \/>\n<meta property=\"og:site_name\" content=\"Subsole\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-06T14:04:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/subsole.fuegoclients.com\/web\/#organization\",\"name\":\"Subsole\",\"url\":\"https:\/\/subsole.fuegoclients.com\/web\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/subsole.fuegoclients.com\/web\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/localhost\/subsole\/wp-content\/uploads\/2022\/06\/logo-subsole.png\",\"contentUrl\":\"http:\/\/localhost\/subsole\/wp-content\/uploads\/2022\/06\/logo-subsole.png\",\"width\":302,\"height\":54,\"caption\":\"Subsole\"},\"image\":{\"@id\":\"https:\/\/subsole.fuegoclients.com\/web\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/subsole.fuegoclients.com\/web\/#website\",\"url\":\"https:\/\/subsole.fuegoclients.com\/web\/\",\"name\":\"Subsole\",\"description\":\"Otro sitio de WordPress\",\"publisher\":{\"@id\":\"https:\/\/subsole.fuegoclients.com\/web\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/subsole.fuegoclients.com\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/subsole.fuegoclients.com\/web\/frutas\/uvas-de-mesa\/variedades\/allison\/\",\"url\":\"https:\/\/subsole.fuegoclients.com\/web\/frutas\/uvas-de-mesa\/variedades\/allison\/\",\"name\":\"Variedad Allison la m\u00e1s dulce &mdash; Subsole\",\"isPartOf\":{\"@id\":\"https:\/\/subsole.fuegoclients.com\/web\/#website\"},\"datePublished\":\"2022-05-30T17:35:01+00:00\",\"dateModified\":\"2022-06-06T14:04:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/subsole.fuegoclients.com\/web\/frutas\/uvas-de-mesa\/variedades\/allison\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/subsole.fuegoclients.com\/web\/frutas\/uvas-de-mesa\/variedades\/allison\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/subsole.fuegoclients.com\/web\/frutas\/uvas-de-mesa\/variedades\/allison\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/subsole.fuegoclients.com\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Variedades\",\"item\":\"https:\/\/subsole.fuegoclients.com\/web\/frutas\/variedades\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Allison\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Variedad Allison la m\u00e1s dulce &mdash; Subsole","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Variedad Allison la m\u00e1s dulce &mdash; Subsole","og_url":"https:\/\/subsole.fuegoclients.com\/web\/frutas\/uvas-de-mesa\/variedades\/allison\/","og_site_name":"Subsole","article_modified_time":"2022-06-06T14:04:09+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/subsole.fuegoclients.com\/web\/#organization","name":"Subsole","url":"https:\/\/subsole.fuegoclients.com\/web\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/subsole.fuegoclients.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/localhost\/subsole\/wp-content\/uploads\/2022\/06\/logo-subsole.png","contentUrl":"http:\/\/localhost\/subsole\/wp-content\/uploads\/2022\/06\/logo-subsole.png","width":302,"height":54,"caption":"Subsole"},"image":{"@id":"https:\/\/subsole.fuegoclients.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/subsole.fuegoclients.com\/web\/#website","url":"https:\/\/subsole.fuegoclients.com\/web\/","name":"Subsole","description":"Otro sitio de WordPress","publisher":{"@id":"https:\/\/subsole.fuegoclients.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/subsole.fuegoclients.com\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/subsole.fuegoclients.com\/web\/frutas\/uvas-de-mesa\/variedades\/allison\/","url":"https:\/\/subsole.fuegoclients.com\/web\/frutas\/uvas-de-mesa\/variedades\/allison\/","name":"Variedad Allison la m\u00e1s dulce &mdash; Subsole","isPartOf":{"@id":"https:\/\/subsole.fuegoclients.com\/web\/#website"},"datePublished":"2022-05-30T17:35:01+00:00","dateModified":"2022-06-06T14:04:09+00:00","breadcrumb":{"@id":"https:\/\/subsole.fuegoclients.com\/web\/frutas\/uvas-de-mesa\/variedades\/allison\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/subsole.fuegoclients.com\/web\/frutas\/uvas-de-mesa\/variedades\/allison\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/subsole.fuegoclients.com\/web\/frutas\/uvas-de-mesa\/variedades\/allison\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/subsole.fuegoclients.com\/web\/"},{"@type":"ListItem","position":2,"name":"Variedades","item":"https:\/\/subsole.fuegoclients.com\/web\/frutas\/variedades\/"},{"@type":"ListItem","position":3,"name":"Allison"}]}]}},"_links":{"self":[{"href":"https:\/\/subsole.fuegoclients.com\/web\/wp-json\/wp\/v2\/variedades\/178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/subsole.fuegoclients.com\/web\/wp-json\/wp\/v2\/variedades"}],"about":[{"href":"https:\/\/subsole.fuegoclients.com\/web\/wp-json\/wp\/v2\/types\/variedades"}],"wp:attachment":[{"href":"https:\/\/subsole.fuegoclients.com\/web\/wp-json\/wp\/v2\/media?parent=178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}