{"id":167,"date":"2022-05-30T14:31:28","date_gmt":"2022-05-30T17:31:28","guid":{"rendered":"http:\/\/localhost\/subsole\/?post_type=variedades&#038;p=167"},"modified":"2022-05-30T14:31:28","modified_gmt":"2022-05-30T17:31:28","slug":"hayward","status":"publish","type":"variedades","link":"https:\/\/subsole.fuegoclients.com\/web\/frutas\/kiwis\/variedades\/hayward\/","title":{"rendered":"Hayward"},"parent":0,"template":"","class_list":["post-167","variedades","type-variedades","status-publish","hentry"],"translation":{"provider":"WPGlobus","version":"2.10.1","language":"es","enabled_languages":["es","en"],"languages":{"es":{"title":true,"content":false,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hayward &mdash; Subsole<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hayward &mdash; Subsole\" \/>\n<meta property=\"og:url\" content=\"https:\/\/subsole.fuegoclients.com\/web\/frutas\/kiwis\/variedades\/hayward\/\" \/>\n<meta property=\"og:site_name\" content=\"Subsole\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/subsole.fuegoclients.com\/web\/#organization\",\"name\":\"Subsole\",\"url\":\"https:\/\/subsole.fuegoclients.com\/web\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/subsole.fuegoclients.com\/web\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/localhost\/subsole\/wp-content\/uploads\/2022\/06\/logo-subsole.png\",\"contentUrl\":\"http:\/\/localhost\/subsole\/wp-content\/uploads\/2022\/06\/logo-subsole.png\",\"width\":302,\"height\":54,\"caption\":\"Subsole\"},\"image\":{\"@id\":\"https:\/\/subsole.fuegoclients.com\/web\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/subsole.fuegoclients.com\/web\/#website\",\"url\":\"https:\/\/subsole.fuegoclients.com\/web\/\",\"name\":\"Subsole\",\"description\":\"Otro sitio de WordPress\",\"publisher\":{\"@id\":\"https:\/\/subsole.fuegoclients.com\/web\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/subsole.fuegoclients.com\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/subsole.fuegoclients.com\/web\/frutas\/kiwis\/variedades\/hayward\/\",\"url\":\"https:\/\/subsole.fuegoclients.com\/web\/frutas\/kiwis\/variedades\/hayward\/\",\"name\":\"Hayward &mdash; Subsole\",\"isPartOf\":{\"@id\":\"https:\/\/subsole.fuegoclients.com\/web\/#website\"},\"datePublished\":\"2022-05-30T17:31:28+00:00\",\"dateModified\":\"2022-05-30T17:31:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/subsole.fuegoclients.com\/web\/frutas\/kiwis\/variedades\/hayward\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/subsole.fuegoclients.com\/web\/frutas\/kiwis\/variedades\/hayward\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/subsole.fuegoclients.com\/web\/frutas\/kiwis\/variedades\/hayward\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/subsole.fuegoclients.com\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Variedades\",\"item\":\"https:\/\/subsole.fuegoclients.com\/web\/frutas\/variedades\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hayward\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hayward &mdash; Subsole","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Hayward &mdash; Subsole","og_url":"https:\/\/subsole.fuegoclients.com\/web\/frutas\/kiwis\/variedades\/hayward\/","og_site_name":"Subsole","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/subsole.fuegoclients.com\/web\/#organization","name":"Subsole","url":"https:\/\/subsole.fuegoclients.com\/web\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/subsole.fuegoclients.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/localhost\/subsole\/wp-content\/uploads\/2022\/06\/logo-subsole.png","contentUrl":"http:\/\/localhost\/subsole\/wp-content\/uploads\/2022\/06\/logo-subsole.png","width":302,"height":54,"caption":"Subsole"},"image":{"@id":"https:\/\/subsole.fuegoclients.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/subsole.fuegoclients.com\/web\/#website","url":"https:\/\/subsole.fuegoclients.com\/web\/","name":"Subsole","description":"Otro sitio de WordPress","publisher":{"@id":"https:\/\/subsole.fuegoclients.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/subsole.fuegoclients.com\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/subsole.fuegoclients.com\/web\/frutas\/kiwis\/variedades\/hayward\/","url":"https:\/\/subsole.fuegoclients.com\/web\/frutas\/kiwis\/variedades\/hayward\/","name":"Hayward &mdash; Subsole","isPartOf":{"@id":"https:\/\/subsole.fuegoclients.com\/web\/#website"},"datePublished":"2022-05-30T17:31:28+00:00","dateModified":"2022-05-30T17:31:28+00:00","breadcrumb":{"@id":"https:\/\/subsole.fuegoclients.com\/web\/frutas\/kiwis\/variedades\/hayward\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/subsole.fuegoclients.com\/web\/frutas\/kiwis\/variedades\/hayward\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/subsole.fuegoclients.com\/web\/frutas\/kiwis\/variedades\/hayward\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/subsole.fuegoclients.com\/web\/"},{"@type":"ListItem","position":2,"name":"Variedades","item":"https:\/\/subsole.fuegoclients.com\/web\/frutas\/variedades\/"},{"@type":"ListItem","position":3,"name":"Hayward"}]}]}},"_links":{"self":[{"href":"https:\/\/subsole.fuegoclients.com\/web\/wp-json\/wp\/v2\/variedades\/167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/subsole.fuegoclients.com\/web\/wp-json\/wp\/v2\/variedades"}],"about":[{"href":"https:\/\/subsole.fuegoclients.com\/web\/wp-json\/wp\/v2\/types\/variedades"}],"wp:attachment":[{"href":"https:\/\/subsole.fuegoclients.com\/web\/wp-json\/wp\/v2\/media?parent=167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}